{"id":9496,"date":"2022-06-30T15:17:24","date_gmt":"2022-06-30T13:17:24","guid":{"rendered":"https:\/\/africagreentec.com.dev.kalayourlife.com\/impactproducts\/cooltainer\/"},"modified":"2024-11-20T14:30:48","modified_gmt":"2024-11-20T13:30:48","slug":"cooltainer","status":"publish","type":"page","link":"https:\/\/www.africagreentec.com\/fr\/impactproducts\/cooltainer\/","title":{"rendered":"Cooltainer"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9496\" class=\"elementor elementor-9496 elementor-814\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c15531 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6c15531\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee1e5da\" data-id=\"ee1e5da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ce0ced elementor-widget elementor-widget-kyl_text_video_image_slant_big\" data-id=\"3ce0ced\" data-element_type=\"widget\" data-widget_type=\"kyl_text_video_image_slant_big.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"kyl_text_video_image_slant_big \">\n            <div class=\"container\">\n                <div class=\"wrapper-right has-video\">\n                                            <video class=\"background_video calc-slant calc-slant-left\" autoplay muted loop playsinline>\n                            <source src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/08\/2023-08-28-AGT_Website_Video_Feed_Cooltainer.mp4\"\n                                    type=\"video\/mp4\">\n                            Your browser does not support the HTML5 Video element.\n                        <\/video>\n                                                            <\/div>\n                <div class=\"wrapper-left\">\n\n                    <div class=\"kyl_breadcrumb\">\n                        <div class=\"wrapper\">\n                            <a class=\"home\" href=\"\/\">\n                                Home                            <\/a>\n\n                                        <span class=\"delimiter\"><\/span>\n                            <a href=\"https:\/\/www.africagreentec.com\/fr\/impactproducts\/\">ImpactProducts<\/a>\n                        <span class=\"delimiter\"><\/span>\n                            <span>Cooltainer<\/span>\n                                    <\/div>\n                    <\/div>\n\n                                        <h1 class=\"headline \">\n                                        <p><span style=\"color: #d0b083;\">Cooltainer<sup>\u00ae<\/sup><\/span> \u2013<br \/>Notre entrep\u00f4t frigorifique autonome pour une agriculture durable<\/p>                <\/h1>\n                \n                                    <div class=\"text\">\n                        <p>Les agriculteurs sont le fondement de l'\u00e9conomie africaine. Nous renfor\u00e7ons les communaut\u00e9s rurales en utilisant notre entrep\u00f4t frigorifique par conteneurs. Avec le Cooltainer, nous minimisons la d\u00e9t\u00e9rioration des denr\u00e9es alimentaires et ouvrons de nouvelles possibilit\u00e9s pour la distribution des aliments. La technologie a \u00e9t\u00e9 d\u00e9velopp\u00e9e en Allemagne et est produite localement en Afrique.<\/p>                    <\/div>\n                \n                \n            <\/div>\n        <\/div>\n        <\/div>\n\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3149ad4 elementor-widget elementor-widget-spacer\" data-id=\"3149ad4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 17-10-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dbf6200 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dbf6200\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a20d66\" data-id=\"8a20d66\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c0a5cb elementor-widget elementor-widget-kyl_product_features\" data-id=\"4c0a5cb\" data-element_type=\"widget\" data-widget_type=\"kyl_product_features.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"kyl_product_features\">\n            <div class=\"container\">\n                <div class=\"wrapper-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1024x640.png\" class=\"image image_desktop\" alt=\"\" title=\"\" srcset=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1024x640.png 1024w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-300x188.png 300w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-768x480.png 768w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1536x961.png 1536w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-2048x1281.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1024x640.png\" class=\"image image_laptop\" alt=\"\" title=\"\" srcset=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1024x640.png 1024w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-300x188.png 300w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-768x480.png 768w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1536x961.png 1536w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-2048x1281.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1024x640.png\" class=\"image image_tablet_extra\" alt=\"\" title=\"\" srcset=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1024x640.png 1024w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-300x188.png 300w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-768x480.png 768w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1536x961.png 1536w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-2048x1281.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1024x640.png\" class=\"image image_tablet\" alt=\"\" title=\"\" srcset=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1024x640.png 1024w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-300x188.png 300w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-768x480.png 768w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1536x961.png 1536w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-2048x1281.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1024x640.png\" class=\"image image_mobile_extra\" alt=\"\" title=\"\" srcset=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1024x640.png 1024w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-300x188.png 300w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-768x480.png 768w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1536x961.png 1536w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-2048x1281.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/10\/Cooltainer_mobile-768x1024.png\" class=\"image image_mobile\" alt=\"\" title=\"\" srcset=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/10\/Cooltainer_mobile-768x1024.png 768w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/10\/Cooltainer_mobile-225x300.png 225w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/10\/Cooltainer_mobile-1152x1536.png 1152w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/10\/Cooltainer_mobile-1536x2048.png 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\n                                                                    <img class=\"feature_icon elementor-repeater-item-0930c77\">\n                        <!--<span class=\"feature_icon elementor-repeater-item-0930c77\"><\/span>-->\n                        <div class=\"feature_text elementor-repeater-item-0930c77\">\n                            <p class=\"headline\">Fonctionnement <br>autonome<\/p>\n                            <p>~ 5 5 kWp <br \/>d'installation<br \/>photovolta\u00efque, <br \/>batteries incluses<\/p>                        <\/div>\n                                                                    <img class=\"feature_icon elementor-repeater-item-6777a6c\">\n                        <!--<span class=\"feature_icon elementor-repeater-item-6777a6c\"><\/span>-->\n                        <div class=\"feature_text elementor-repeater-item-6777a6c\">\n                            <p class=\"headline\">2 - 10 \u00b0C temp\u00e9rature int\u00e9rieure<\/p>\n                            <p>pour une temp\u00e9rature<br \/>ambiante jusqu'\u00e0 <br \/>35 \u00b0C<\/p>                        <\/div>\n                                                                    <img class=\"feature_icon elementor-repeater-item-a65b989\">\n                        <!--<span class=\"feature_icon elementor-repeater-item-a65b989\"><\/span>-->\n                        <div class=\"feature_text elementor-repeater-item-a65b989\">\n                            <p class=\"headline\">21 m<sup>3<\/sup> de chambre froide<\/p>\n                            <p>pour minimiser les pertes<br \/>de produits alimentaires<\/p>                        <\/div>\n                                                                    <img class=\"feature_icon elementor-repeater-item-79da403\">\n                        <!--<span class=\"feature_icon elementor-repeater-item-79da403\"><\/span>-->\n                        <div class=\"feature_text elementor-repeater-item-79da403\">\n                            <p class=\"headline\">Plug & Play<\/p>\n                            <p>facile \u00e0 utiliser et \u00e0 surveiller \u00e0 distance<\/p>                        <\/div>\n                    \n                <\/div>\n            <\/div>\n        <\/div>\n\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5b9d90 elementor-widget elementor-widget-spacer\" data-id=\"d5b9d90\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18ac3ab elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"18ac3ab\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46250ec\" data-id=\"46250ec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fde2866 view-default elementor-widget elementor-widget-kyl_image_teaser_slant_big\" data-id=\"fde2866\" data-element_type=\"widget\" data-widget_type=\"kyl_image_teaser_slant_big.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"kyl_image_teaser_slant_big color-off-yellow\">\n            <div class=\"container\">\n\n\t\t\t\t\n            <div class=\"wrapper-image\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Bara_Ndiaye-1024x683.jpg\" class=\"background_image\" alt=\"Bara_Ndiaye\" title=\"Bara_Ndiaye\" srcset=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Bara_Ndiaye-1024x683.jpg 1024w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Bara_Ndiaye-300x200.jpg 300w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Bara_Ndiaye-768x512.jpg 768w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Bara_Ndiaye.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t\t\t\t                    <div class=\"imagetext\">\n\t\t\t\t\t\tBara N\u2019diaye,<br \/>\nAgriculteur, N\u2019diob, Senegal                    <\/div>\n\t\t\t\t\n\t\t\t\t                    <span class=\"quote quote_desktop\">\u201c<\/span>\n\t\t\t\t            <\/div>\n            <div class=\"wrapper-text\">\n\n\t\t\t\t                    <span class=\"quote quote_mobile\">\u201c<\/span>\n                    <span class=\"quote quote_tablet\">\u201c<\/span>\n\t\t\t\t\n                <a href=\"#\"                  class=\"content\">\n\n\t\t\t\t\n\t\t\t\t                    <div class=\"text\">\n\t\t\t\t\t\t<p>Le Cooltainer m'aidera \u00e0 conserver ma r\u00e9colte fra\u00eeche plus longtemps, ce qui me permettra de la vendre \u00e0 un bon prix sur le march\u00e9 pendant une p\u00e9riode plus longue.<\/p>                    <\/div>\n\t\t\t\t\n\t\t\t\t                    <div class=\"imagetext\">\n\t\t\t\t\t\tBara N\u2019diaye,<br \/>\nAgriculteur, N\u2019diob, Senegal                    <\/div>\n\t\t\t\t\n\t\t\t\t                    <div class=\"is-link link\">\n                        <span>\n                            Link                        <\/span>\n                    <\/div>\n\t\t\t\t            <\/a>\n\n        <\/div>\n        <\/div>\n\t\t        <\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bbb7c4 elementor-widget elementor-widget-spacer\" data-id=\"3bbb7c4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af39f15 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af39f15\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aefc0bb\" data-id=\"aefc0bb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df9ee4d elementor-widget elementor-widget-kyl_icon_text_video_image_medium\" data-id=\"df9ee4d\" data-element_type=\"widget\" data-widget_type=\"kyl_icon_text_video_image_medium.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"kyl_icon_text_video_image_medium\">\n            <div class=\"container is-left\">\n                <div class=\"wrapper-media has-image\">\n\n                                            <img decoding=\"async\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/05\/Importe-243-von-326-scaled.jpg\"\n                             title=\"Importe - 243 von 326\"\n                             alt=\"Importe - 243 von 326\">\n                    \n                    \n                    \n                <\/div>\n                <div class=\"wrapper-text\">\n\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Icons_Kuehlung_pb-150x150.png\" class=\"icon\" alt=\"\" srcset=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Icons_Kuehlung_pb-150x150.png 150w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Icons_Kuehlung_pb-300x300.png 300w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Icons_Kuehlung_pb.png 418w\" sizes=\"auto, (max-width: 80px) 100vw, 80px\" \/>                    \n                                        <h3 class=\"headline\">\n                                        <p>40 % des r\u00e9coltes de l\u00e9gumes et de fruits p\u00e9rissent en Afrique subsaharienne*<\/p>                <\/h3>\n                \n                                    <div class=\"text\">\n                        <p>En raison de l'absence de cha\u00eenes du froid, une grande partie des r\u00e9coltes en Afrique subsaharienne ne peut pas \u00eatre stock\u00e9e longtemps et des aliments pr\u00e9cieux se d\u00e9t\u00e9riorent chaque jour au soleil. Cela entra\u00eene non seulement des p\u00e9nuries alimentaires, mais aussi des \u00e9missions \u00e9lev\u00e9es de CO<sub>2<\/sub>. De forts changements climatiques rendent les conditions encore plus difficiles pour les agriculteurs. *<a href=\"https:\/\/www.fao.org\/news\/story\/fr\/item\/1142074\/icode\/\" target=\"_blank\" rel=\"noopener\">Source FAO<\/a><\/p>                    <\/div>\n                \n                \n            <\/div>\n        <\/div>\n        <\/div>\n\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8675184 elementor-widget elementor-widget-spacer\" data-id=\"8675184\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aae89d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aae89d9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b1526d7\" data-id=\"b1526d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66d0f42 elementor-widget elementor-widget-kyl_text_image_feature_medium\" data-id=\"66d0f42\" data-element_type=\"widget\" data-widget_type=\"kyl_text_image_feature_medium.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"kyl_text_image_feature_medium\">\n            <div class=\"container is-left\">\n                <div class=\"wrapper-right\">\n\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_Oben_green.png\" title=\"Cooltainer_Oben_green\" alt=\"Cooltainer_Oben_green\" loading=\"lazy\" \/>                        <!--<div class=\"background_image\" style=\"background-image: url('https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_Oben_green.png')\"><\/div>-->\n\t\t\t\t\t\n\t\t\t\t\t\n                <\/div>\n                <div class=\"wrapper-left\">\n\n\t\t\t\t\t                        <h6 class=\"subheadline\">Raffra\u00eechissant. Autonome. Innovant.<\/h6>\n\t\t\t\t\t\n\t\t\t\t\t<h3                    class=\"headline\">Cooltainer \u2013 Notre entrep\u00f4t frigorifique autonome garde la r\u00e9colte fra\u00eeche                <\/h3>\n\t\t\t\t                    <div class=\"text\">\n\t\t\t\t\t\t<p>Le Cooltainer de 20 pieds peut fonctionner aussi bien connect\u00e9 au r\u00e9seau que de mani\u00e8re totalement autonome, gr\u00e2ce \u00e0 l'installation solaire int\u00e9gr\u00e9e de 5 kWp. Si nous exploitons nous-m\u00eames le entrep\u00f4t frigorifique, les agriculteurs peuvent louer des cases pour leurs r\u00e9coltes dans le dispositif. Pour cela, nous avons mis au point un processus bien con\u00e7u qui rend l'utilisation aussi simple que possible pour nos clients. Mais le entrep\u00f4t frigorifique peut aussi \u00eatre achet\u00e9 comme solution compl\u00e8te ou \u00eatre lou\u00e9 et exploit\u00e9 individuellement.<\/p>                    <\/div>\n\t\t\t\t\n            <\/div>\n        <\/div>\n        <\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a451453 elementor-widget elementor-widget-spacer\" data-id=\"a451453\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aabef3d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aabef3d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eb473b3\" data-id=\"eb473b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b6530d width-boxed elementor-widget elementor-widget-kyl_images\" data-id=\"8b6530d\" data-element_type=\"widget\" data-widget_type=\"kyl_images.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"kyl_images\" data-count=\"1\">\n\n\t\t\t                <div class=\"image image1 \">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/08\/DSC09851_Edited.png\" title=\"DSC09851_Edited\" alt=\"DSC09851_Edited\" loading=\"lazy\" \/>\n\t\t\t\t\t                <\/div>\n\t\t\t\n\t\t\t\n\n        <\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3522deb elementor-widget elementor-widget-spacer\" data-id=\"3522deb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f531bf elementor-widget elementor-widget-kyl_text\" data-id=\"2f531bf\" data-element_type=\"widget\" data-widget_type=\"kyl_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"kyl_text is-center\">\n            <div class=\"container\">\n\t\t\t\t                <h2 class=\"headline\">\n\t\t\t\tLa r\u00e9frig\u00e9ration en tant que service \u2013 Le mod\u00e8le commercial du Cooltainer            <\/h2>\n\t\t\t\n\t\t\t                <div class=\"text\">\n\t\t\t\t\t<p>Le Cooltainer offre aux agriculteurs un espace de refroidissement pour leurs r\u00e9coltes afin qu'elles ne se g\u00e2tent pas sous la chaleur. Cela est particuli\u00e8rement utile pendant la p\u00e9riode de r\u00e9colte, par exemple lorsque de nombreuses tomates sont r\u00e9colt\u00e9es en peu de temps, mais qu'elles ne peuvent pas toutes \u00eatre vendues imm\u00e9diatement. Avec le Cooltainer, nos clients b\u00e9n\u00e9ficient de la possibilit\u00e9 de louer individuellement une chambre froide lorsqu'ils en ont besoin. Ils peuvent ainsi obtenir de bons prix pour leurs marchandises sur une p\u00e9riode plus longue et les aliments ne se d\u00e9t\u00e9riorent pas trop t\u00f4t.<\/p>                <\/div>\n\t\t\t\n\t\t\t        <\/div>\n        <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c477a0b elementor-widget elementor-widget-spacer\" data-id=\"c477a0b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e60e60 elementor-widget elementor-widget-kyl_key_figure_counter\" data-id=\"8e60e60\" data-element_type=\"widget\" data-widget_type=\"kyl_key_figure_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"kyl_key_figure_counter\" data-figure-separator=\"point\">\n            <div class=\"container\">\n\n\t\t\t\t            <div class=\"wrapper\">\n\n\t\t\t\t                    <div class=\"key_figure\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Icons_Box_Vermietung_pb-150x150.png\" class=\"icon\" alt=\"\" srcset=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Icons_Box_Vermietung_pb-150x150.png 150w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Icons_Box_Vermietung_pb-300x300.png 300w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Icons_Box_Vermietung_pb.png 418w\" sizes=\"auto, (max-width: 80px) 100vw, 80px\" \/>                        <div class=\"figure\" data-is-year=\"\" data-figure=\"50\" data-starting-figure=\"0\">0<\/div>\n\n\t\t\t\t\t\t                            <div class=\"text\">\n\t\t\t\t\t\t\t\t<strong>Bo\u00eetes de litres<\/strong><br \/>\nLes clients peuvent<br \/>\nlouer un bac par <br \/>\njour\/semaine\/mois                            <\/div>\n\t\t\t\t\t\t                    <\/div>\n\t\t\t\t                    <div class=\"key_figure\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Icons_Box_pb-150x150.png\" class=\"icon\" alt=\"\" srcset=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Icons_Box_pb-150x150.png 150w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Icons_Box_pb-300x300.png 300w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Icons_Box_pb.png 417w\" sizes=\"auto, (max-width: 80px) 100vw, 80px\" \/>                        <div class=\"figure\" data-is-year=\"\" data-figure=\"180\" data-starting-figure=\"0\">0<\/div>\n\n\t\t\t\t\t\t                            <div class=\"text\">\n\t\t\t\t\t\t\t\t<strong>Bacs<\/strong><br \/>\nsont plac\u00e9es dans le<br \/>\nCooltainer et permettent<br \/>\nun stockage pratiques                            <\/div>\n\t\t\t\t\t\t                    <\/div>\n\t\t\t\t                    <div class=\"key_figure\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Icons_Mitarbeiter_pb-150x150.png\" class=\"icon\" alt=\"\" srcset=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Icons_Mitarbeiter_pb-150x150.png 150w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Icons_Mitarbeiter_pb-300x300.png 300w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Icons_Mitarbeiter_pb.png 417w\" sizes=\"auto, (max-width: 80px) 100vw, 80px\" \/>                        <div class=\"figure\" data-is-year=\"\" data-figure=\"2\" data-starting-figure=\"0\">0<\/div>\n\n\t\t\t\t\t\t                            <div class=\"text\">\n\t\t\t\t\t\t\t\t<strong>Collaborateurs<\/strong><br \/>\nde pr\u00e9f\u00e9rence des femmes<br \/>\nlocales pour g\u00e9rer le Cooltainer<br \/>\net aider les clients                            <\/div>\n\t\t\t\t\t\t                    <\/div>\n\t\t\t\t            <\/div>\n        <\/div>\n        <\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e718a12 elementor-widget elementor-widget-spacer\" data-id=\"e718a12\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16fa3ae elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"16fa3ae\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cc47f12\" data-id=\"cc47f12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26ad6df elementor-widget elementor-widget-kyl_teaser_contact\" data-id=\"26ad6df\" data-element_type=\"widget\" data-widget_type=\"kyl_teaser_contact.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"kyl_teaser_contact color-very-light-brown\">\n\n            <div class=\"container is-left\">\n\n                <div class=\"wrapper wrapper_image\">\n\n                    <div class=\"image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2024\/11\/Staff_Illustration_Teaser_Alireza_Derakhshan_BC_23-06-01-1.png\" title=\"Staff_Illustration_Teaser_Alireza_Derakhshan_BC_23-06-01 (1)\" alt=\"Staff_Illustration_Teaser_Alireza_Derakhshan_BC_23-06-01 (1)\" loading=\"lazy\" \/>\n\t\t\t\t\t\t<div class=\"caption\"><p><strong>Alireza<\/strong><br \/>Products Manager - AGT AG<\/p><\/div>                    <\/div>\n                <\/div>\n                <div class=\"wrapper wrapper_text\">\n\n\t\t\t\t\t<h3\n                            class=\"headline\">Vous \u00eates int\u00e9ress\u00e9(e) par notre Cooltainer ? Prenez contact avec nous.<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t                        <div class=\"is-button link\">\n                            <a href=\"mailto:ibd@africagreentec.com\"  >Contact<\/a>\n                        <\/div>\n\t\t\t\t\t                <\/div>\n            <\/div>\n        <\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72d5502 elementor-widget elementor-widget-spacer\" data-id=\"72d5502\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bcf0b48 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bcf0b48\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c659c4c\" data-id=\"c659c4c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbd86d1 elementor-widget elementor-widget-kyl_double_image\" data-id=\"bbd86d1\" data-element_type=\"widget\" data-widget_type=\"kyl_double_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"kyl_double_image\">\n            <div class=\"container\" style=\"\n                    background-image: -webkit-image-set(\n                    url('https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/10\/ImpactSite_Illustration_Amali_Icon-1.png') 2x,\n                    url('https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/10\/ImpactSite_Illustration_Amali_Icon-1.png') 1x\n                    );\n                    background-image: image-set(\n                    url('https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/10\/ImpactSite_Illustration_Amali_Icon-1.png') 2x,\n                    url('https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/10\/ImpactSite_Illustration_Amali_Icon-1.png') 1x\n                    );\n                    \">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1202\" height=\"1232\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_zoom.png\" class=\"image\" alt=\"\" srcset=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_zoom.png 1202w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_zoom-293x300.png 293w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_zoom-999x1024.png 999w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_zoom-768x787.png 768w\" sizes=\"auto, (max-width: 1202px) 100vw, 1202px\" \/>            <\/div>\n        <\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bede891 elementor-widget elementor-widget-spacer\" data-id=\"bede891\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b0ecc7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b0ecc7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-993ce46\" data-id=\"993ce46\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-918babe elementor-widget elementor-widget-kyl_text\" data-id=\"918babe\" data-element_type=\"widget\" data-widget_type=\"kyl_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"kyl_text is-center\">\n            <div class=\"container\">\n\t\t\t\t                <h2 class=\"headline\">\n\t\t\t\tLe Cooltainer dans le cadre de notre solution holistique \u2013 L'ImpactSite            <\/h2>\n\t\t\t\n\t\t\t                <div class=\"text\">\n\t\t\t\t\t<p>D\u00e9couvrez notre ImpactSite et comment le Cooltainer, combin\u00e9 \u00e0 l'acc\u00e8s \u00e0 une \u00e9lectricit\u00e9 solaire durable et fiable, \u00e0 l'eau potable et \u00e0 Internet, permet \u00e0 des communaut\u00e9s enti\u00e8res de devenir plus autonomes et de se d\u00e9velopper.<\/p>                <\/div>\n\t\t\t\n\t\t\t                <div class=\"is-link link\">\n                    <a href=\"https:\/\/www.africagreentec.com\/fr\/impactsite\/\"  >\n\t\t\t\t\t\tImpactSite                    <\/a>\n                <\/div>\n\t\t\t        <\/div>\n        <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9aff42e elementor-widget elementor-widget-spacer\" data-id=\"9aff42e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-171e26e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"171e26e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e81166d\" data-id=\"e81166d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6541bb elementor-widget elementor-widget-kyl_teaser_contentpage\" data-id=\"e6541bb\" data-element_type=\"widget\" data-widget_type=\"kyl_teaser_contentpage.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"kyl_teaser_contentpage color-off-yellow\">\n\n            \n            <div class=\"swiper\">\n                <div class=\"swiper-wrapper\">\n                                            <div class=\"swiper-slide\">\n                                                        <a href=\"https:\/\/www.africagreentec.com\/fr\/impactproducts\/coolup\/\">\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"172\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/09\/CoolUP-1-300x172.png\" class=\"image\" alt=\"CoolUP\" title=\"CoolUP\" srcset=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/09\/CoolUP-1-300x172.png 300w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/09\/CoolUP-1-1024x589.png 1024w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/09\/CoolUP-1-768x441.png 768w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/09\/CoolUP-1-1536x883.png 1536w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/09\/CoolUP-1-2048x1177.png 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                <div class=\"title\">\n                                    <h2>CoolUP<\/h2>\n<p><span style=\"font-weight: 400\">Nous avons mis au point un r\u00e9frig\u00e9rateur innovant et efficace, sp\u00e9cialement con\u00e7u pour fonctionner \u00e0 l&rsquo;\u00e9nergie solaire.<\/span><\/p>\n                                <\/div>\n                                                                <span class=\"icon\"><\/span>\n                            <\/a>\n                                                <\/div>\n                                            <div class=\"swiper-slide\">\n                                                        <a href=\"https:\/\/www.africagreentec.com\/fr\/impactproducts\/pumpup\/\">\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/12\/PumpUP-300x169.png\" class=\"image\" alt=\"PumpUP\" title=\"PumpUP\" srcset=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/12\/PumpUP-300x169.png 300w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/12\/PumpUP.png 696w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                <div class=\"title\">\n                                    <h2>PumpUP<\/h2>\n<p><span style=\"font-weight: 400\">Nous soutenons les agriculteurs africains avec nos pompes de forage solaires innovantes et tr\u00e8s efficaces.<\/span><\/p>\n                                <\/div>\n                                                                <span class=\"icon\"><\/span>\n                            <\/a>\n                                                <\/div>\n                                            <div class=\"swiper-slide\">\n                                                        <a href=\"https:\/\/www.africagreentec.com\/fr\/impactproducts\/streetup\/\">\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"226\" src=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/11\/IMG_20230513_130034-300x226.jpg\" class=\"image\" alt=\"IMG_20230513_130034\" title=\"IMG_20230513_130034\" srcset=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/11\/IMG_20230513_130034-300x226.jpg 300w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/11\/IMG_20230513_130034-1024x771.jpg 1024w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/11\/IMG_20230513_130034-768x578.jpg 768w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/11\/IMG_20230513_130034-1536x1157.jpg 1536w, https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/11\/IMG_20230513_130034-2048x1542.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                <div class=\"title\">\n                                    <h2>StreetUP<\/h2>\n<p><span style=\"font-weight: 400\">\u00c9clairage public solaire pour des communaut\u00e9s <\/span><span style=\"font-weight: 400\">en s\u00e9curit\u00e9<\/span><span style=\"font-weight: 400\">.<\/span><\/p>\n                                <\/div>\n                                                                <span class=\"icon\"><\/span>\n                            <\/a>\n                                                <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be1a900 elementor-widget elementor-widget-spacer\" data-id=\"be1a900\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-935ff46 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"935ff46\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c943f8\" data-id=\"5c943f8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d84054 elementor-widget elementor-widget-kyl_newsletter\" data-id=\"3d84054\" data-element_type=\"widget\" data-widget_type=\"kyl_newsletter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"kyl_newsletter\">\n\n            \n            <lottie-player class=\"icon icon_lottie is-default\" src=\"\/wp-content\/themes\/kyltheme\/assets\/lottiefiles\/AGT_14_Piktogramm_Brief_dunkel.json\" loop autoplay><\/lottie-player>\n            <lottie-player class=\"icon icon_lottie is-success is-hidden\" src=\"\/wp-content\/themes\/kyltheme\/assets\/lottiefiles\/AGT_15_Piktogramm_Konfetti_dunkel.json\" loop><\/lottie-player>\n\n                            <h3 class=\"headline\">\n                    Impact Newsletter                <\/h3>\n            \n                            <div class=\"text is-default\">\n                    <p><span style=\"font-weight: 400;\">Vous souhaitez<\/span> \u00eatre tenu(e) au courant sur nos produits ? <br \/><span style=\"font-weight: 400;\">inscrivez-vous<\/span> \u00e0 notre newsletter Impact.<\/p>                <\/div>\n            \n            \n            \n            <form action=\"\" method=\"post\">\n                <p class=\"wrapper_email\">\n                    <label>\n                        <input type=\"email\" name=\"email\" placeholder=\"E-Mail*\" required>\n                    <\/label>\n                <\/p>\n                <p class=\"wrapper_name\" style=\"display: none\">\n                    <label>\n                        <input type=\"text\" name=\"fname\" placeholder=\"Vorname*\" required>\n                    <\/label><br>\n                    <label>\n                        <input type=\"text\" name=\"lname\" placeholder=\"Nachname*\" required>\n                    <\/label>\n                <\/p>\n                <p class=\"wrapper_submit\">\n                    <label>\n                        <input class=\"is-button\" type=\"submit\"\n                               value=\"Abonnez-vous\">\n                    <\/label>\n                <\/p>\n            <\/form>\n\n                            <div class=\"quote\">\n                    WE DO.                <\/div>\n                    <\/div>\n\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Your browser does not support the HTML5 Video element. Home ImpactProducts Cooltainer Cooltainer\u00ae \u2013Notre entrep\u00f4t frigorifique autonome pour une agriculture durable Les agriculteurs sont le fondement de l&rsquo;\u00e9conomie africaine. Nous renfor\u00e7ons les communaut\u00e9s rurales en utilisant notre entrep\u00f4t frigorifique par conteneurs. Avec le Cooltainer, nous minimisons la d\u00e9t\u00e9rioration des denr\u00e9es alimentaires et ouvrons de nouvelles [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":8928,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9496","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cooltainer - Africa GreenTec AG<\/title>\n<meta name=\"description\" content=\"Notre entrep\u00f4t frigorifique renouvelable offre une technologie de refroidissement pour l&#039;agriculture durable et la conservation des aliments.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africagreentec.com\/fr\/impactproducts\/cooltainer\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cooltainer - Africa GreenTec AG\" \/>\n<meta property=\"og:description\" content=\"Notre entrep\u00f4t frigorifique renouvelable offre une technologie de refroidissement pour l&#039;agriculture durable et la conservation des aliments.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africagreentec.com\/fr\/impactproducts\/cooltainer\/\" \/>\n<meta property=\"og:site_name\" content=\"Africa GreenTec AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/AfricaGreenTec\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-20T13:30:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1024x640.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AfricaGreenTec\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africagreentec.com\/fr\/impactproducts\/cooltainer\/\",\"url\":\"https:\/\/www.africagreentec.com\/fr\/impactproducts\/cooltainer\/\",\"name\":\"Cooltainer - Africa GreenTec AG\",\"isPartOf\":{\"@id\":\"https:\/\/www.africagreentec.com\/fr\/#website\"},\"datePublished\":\"2022-06-30T13:17:24+00:00\",\"dateModified\":\"2024-11-20T13:30:48+00:00\",\"description\":\"Notre entrep\u00f4t frigorifique renouvelable offre une technologie de refroidissement pour l'agriculture durable et la conservation des aliments.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africagreentec.com\/fr\/impactproducts\/cooltainer\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africagreentec.com\/fr\/impactproducts\/cooltainer\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africagreentec.com\/fr\/impactproducts\/cooltainer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.africagreentec.com\/fr\/?page_id=111914\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ImpactProducts\",\"item\":\"https:\/\/www.africagreentec.com\/fr\/impactproducts\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cooltainer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africagreentec.com\/fr\/#website\",\"url\":\"https:\/\/www.africagreentec.com\/fr\/\",\"name\":\"Africa GreenTec AG\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.africagreentec.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africagreentec.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.africagreentec.com\/fr\/#organization\",\"name\":\"Africa GreenTec AG\",\"url\":\"https:\/\/www.africagreentec.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africagreentec.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/01\/AGT_Logo_BC-22-07-22.svg\",\"contentUrl\":\"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/01\/AGT_Logo_BC-22-07-22.svg\",\"width\":580,\"height\":249,\"caption\":\"Africa GreenTec AG\"},\"image\":{\"@id\":\"https:\/\/www.africagreentec.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/de-de.facebook.com\/AfricaGreenTec\/\",\"https:\/\/twitter.com\/AfricaGreenTec\",\"https:\/\/de.linkedin.com\/company\/africa-greentec\",\"https:\/\/www.instagram.com\/africa_greentec\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cooltainer - Africa GreenTec AG","description":"Notre entrep\u00f4t frigorifique renouvelable offre une technologie de refroidissement pour l'agriculture durable et la conservation des aliments.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africagreentec.com\/fr\/impactproducts\/cooltainer\/","og_locale":"fr_FR","og_type":"article","og_title":"Cooltainer - Africa GreenTec AG","og_description":"Notre entrep\u00f4t frigorifique renouvelable offre une technologie de refroidissement pour l'agriculture durable et la conservation des aliments.","og_url":"https:\/\/www.africagreentec.com\/fr\/impactproducts\/cooltainer\/","og_site_name":"Africa GreenTec AG","article_publisher":"https:\/\/de-de.facebook.com\/AfricaGreenTec\/","article_modified_time":"2024-11-20T13:30:48+00:00","og_image":[{"url":"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/02\/Cooltainer_45_green-2-1024x640.png"}],"twitter_card":"summary_large_image","twitter_site":"@AfricaGreenTec","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.africagreentec.com\/fr\/impactproducts\/cooltainer\/","url":"https:\/\/www.africagreentec.com\/fr\/impactproducts\/cooltainer\/","name":"Cooltainer - Africa GreenTec AG","isPartOf":{"@id":"https:\/\/www.africagreentec.com\/fr\/#website"},"datePublished":"2022-06-30T13:17:24+00:00","dateModified":"2024-11-20T13:30:48+00:00","description":"Notre entrep\u00f4t frigorifique renouvelable offre une technologie de refroidissement pour l'agriculture durable et la conservation des aliments.","breadcrumb":{"@id":"https:\/\/www.africagreentec.com\/fr\/impactproducts\/cooltainer\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africagreentec.com\/fr\/impactproducts\/cooltainer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.africagreentec.com\/fr\/impactproducts\/cooltainer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.africagreentec.com\/fr\/?page_id=111914"},{"@type":"ListItem","position":2,"name":"ImpactProducts","item":"https:\/\/www.africagreentec.com\/fr\/impactproducts\/"},{"@type":"ListItem","position":3,"name":"Cooltainer"}]},{"@type":"WebSite","@id":"https:\/\/www.africagreentec.com\/fr\/#website","url":"https:\/\/www.africagreentec.com\/fr\/","name":"Africa GreenTec AG","description":"","publisher":{"@id":"https:\/\/www.africagreentec.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africagreentec.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.africagreentec.com\/fr\/#organization","name":"Africa GreenTec AG","url":"https:\/\/www.africagreentec.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africagreentec.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/01\/AGT_Logo_BC-22-07-22.svg","contentUrl":"https:\/\/www.africagreentec.com\/wp-content\/uploads\/2023\/01\/AGT_Logo_BC-22-07-22.svg","width":580,"height":249,"caption":"Africa GreenTec AG"},"image":{"@id":"https:\/\/www.africagreentec.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/AfricaGreenTec\/","https:\/\/twitter.com\/AfricaGreenTec","https:\/\/de.linkedin.com\/company\/africa-greentec","https:\/\/www.instagram.com\/africa_greentec\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.africagreentec.com\/fr\/wp-json\/wp\/v2\/pages\/9496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africagreentec.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.africagreentec.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.africagreentec.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africagreentec.com\/fr\/wp-json\/wp\/v2\/comments?post=9496"}],"version-history":[{"count":98,"href":"https:\/\/www.africagreentec.com\/fr\/wp-json\/wp\/v2\/pages\/9496\/revisions"}],"predecessor-version":[{"id":92935,"href":"https:\/\/www.africagreentec.com\/fr\/wp-json\/wp\/v2\/pages\/9496\/revisions\/92935"}],"up":[{"embeddable":true,"href":"https:\/\/www.africagreentec.com\/fr\/wp-json\/wp\/v2\/pages\/8928"}],"wp:attachment":[{"href":"https:\/\/www.africagreentec.com\/fr\/wp-json\/wp\/v2\/media?parent=9496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}